{"id":6016,"date":"2026-05-01T19:51:44","date_gmt":"2026-05-01T19:51:44","guid":{"rendered":"https:\/\/warnerfitzmartin.com\/?page_id=6016"},"modified":"2026-08-27T08:38:00","modified_gmt":"2026-08-27T08:38:00","slug":"abogado-de-accidentes-de-uber-en-boca-raton","status":"publish","type":"page","link":"https:\/\/warnerfitzmartin.com\/es\/boca-raton-uber-accident-lawyer\/","title":{"rendered":"Abogado de accidentes de Uber en Boca Raton"},"content":{"rendered":"<h2 data-pm-slice=\"0 0 []\"><strong>Abogado de accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h2>\n<p>Si result\u00f3 herido en un accidente de Uber en Boca Rat\u00f3n, es posible que est\u00e9 lidiando con lesiones graves y no sepa c\u00f3mo reclamar el pago de sus facturas m\u00e9dicas y otras p\u00e9rdidas. Nuestro <a href=\"https:\/\/warnerfitzmartin.com\/\">Abogado de accidentes de Uber en Boca Rat\u00f3n, FL<\/a> sabe que cuando se suma el factor de una empresa externa de transporte compartido, esto puede complicar la situaci\u00f3n. En Warner &amp; Fitzmartin Personal Injury Lawyers, hemos manejado casos de lesiones personales en todo el sur de Florida durante m\u00e1s de 20 a\u00f1os. Sabemos c\u00f3mo funcionan las reclamaciones por accidentes de transporte compartido y c\u00f3mo abogar por su recuperaci\u00f3n.<\/p>\n<h2><strong>\u00bfPor qu\u00e9 elegir a Warner &amp; Fitzmartin Personal Injury Lawyers para casos de accidentes de Uber en Boca Rat\u00f3n, FL?<\/strong><\/h2>\n<h3><strong>Ra\u00edces Profundas en Ley de Lesiones Personales del Sur de Florida<\/strong><\/h3>\n<p>Abogado <a href=\"https:\/\/warnerfitzmartin.com\/about-aaron-warner\/\">Aaron Warner<\/a> naci\u00f3 y se cri\u00f3 en el sur de Florida y ha pasado toda su carrera representando a v\u00edctimas de lesiones aqu\u00ed. Es un abogado de litigios civiles admitido en el Colegio de Abogados de Florida, el Tribunal de Distrito de EE. UU. para el Distrito Sur de Florida y el Tribunal de Distrito de EE. UU. para el Distrito Medio de Florida. Nombrado<a href=\"https:\/\/www.superlawyers.com\/\"> Super Lawyers Rising Star<\/a> cada a\u00f1o desde 2019 y reconocido por<a href=\"https:\/\/www.floridatrend.com\/legal-elite\"> Florida Trend's Legal Elite<\/a>, ha construido la empresa bas\u00e1ndose en resultados consistentes que marcan la diferencia para sus clientes.<\/p>\n<p>Abogado <a href=\"https:\/\/warnerfitzmartin.com\/about-elissa-fitzmartin\/\">Elissa Fitzmartin<\/a> es una abogada litigante que se gradu\u00f3 Magna Cum Laude de la Facultad de Derecho de la Universidad de Miami, donde fue miembro de la Law Review, el Moot Court y la Federal Appellate Clinic. Ha sido nombrada<a href=\"https:\/\/www.bestlawyers.com\/\"> Mejores Abogados<\/a> \u201cPromesas en Litigios de Lesiones Personales del Demandante\u201d, reconocido como Abogado Destacado por el<a href=\"https:\/\/bocamag.com\/\"> Boca Raton Observer<\/a>, y actualmente forma parte de la Junta Directiva de la <a href=\"https:\/\/southpalmbeachbar.org\/\">Asociaci\u00f3n de Abogados del Sur del Condado de Palm Beach<\/a>. Ella ha manejado casos no solo en Florida sino en m\u00faltiples estados, incluyendo la corte federal de Dakota del Sur.<\/p>\n<h3><strong>Un historial que habla por s\u00ed solo<\/strong><\/h3>\n<p>Hemos recuperado<a href=\"https:\/\/warnerfitzmartin.com\/case-results\/\"> millones de d\u00f3lares<\/a> para v\u00edctimas de lesiones en todo el sur de Florida. Tanto Aaron como Elissa son miembros vitalicios de la<a href=\"https:\/\/www.milliondollaradvocates.com\/\"> Foro de Abogados de un Mill\u00f3n de D\u00f3lares<\/a>, una distinci\u00f3n reservada a los abogados que han logrado veredictos o acuerdos por un valor de 1 000 000 de d\u00f3lares o m\u00e1s. Esto demuestra nuestra dedicaci\u00f3n y capacidad para conseguir los resultados que nuestros clientes necesitan en algunos de los momentos m\u00e1s dif\u00edciles.<\/p>\n<h3><strong>Abogados litigantes, no solo negociadores<\/strong><\/h3>\n<p>Si bien algunos bufetes de abogados pueden inclinarse a resolver todos los casos, nosotros preparamos cada caso como si pudiera ir a juicio. Esa postura cambia la forma en que las compa\u00f1\u00edas de seguros responden a nuestras demandas y negociaciones. Las aseguradoras corporativas de Uber saben cu\u00e1ndo est\u00e1n tratando con abogados que realmente llevar\u00e1n un caso a un jurado. Por lo tanto, si no se llega a una resoluci\u00f3n justa, estamos listos para ir a la corte en su nombre.<\/p>\n<h3><strong>Sin honorarios a menos que ganemos<\/strong><\/h3>\n<p>Manejamos casos de accidentes de Uber con honorarios de contingencia. Esto significa que no nos debe nada a menos que recuperemos una compensaci\u00f3n para usted. No hay dep\u00f3sito inicial, no cobramos por hora y nuestra consulta inicial es gratuita. Esta estructura nos permite ayudar a m\u00e1s personas que podr\u00edan estar pasando por dificultades financieras y no necesitan un gasto adicional inmediato.<\/p>\n<p>\u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n<p><em>\u201cLa mejor abogada que he tenido. Antes de Elissa, tuve otro abogado que no respond\u00eda y no estaba haciendo el trabajo. Contrat\u00e9 a Elissa y resolvi\u00f3 mi caso de accidente automovil\u00edstico en 3 meses. Me consigui\u00f3 un 25% m\u00e1s por mi p\u00e9rdida total. Ella ide\u00f3 una estrategia para que obtuviera 9 veces m\u00e1s de lo que pens\u00e1bamos originalmente, debido a su agresividad y estrategia. No puedo agradecerle lo suficiente.\u201d<\/em> \u2014 Lee ImageHunter<\/p>\n<p>Lee m\u00e1s rese\u00f1as en nuestro <a href=\"https:\/\/maps.app.goo.gl\/b87XYUKqhDMeBg4s8\">Perfil de Negocio de Google.<\/a><\/p>\n<h2><strong>Tipos de Casos de Accidentes de Uber que Manejamos en Boca Raton<\/strong><\/h2>\n<p>Los choques de Uber pueden ocurrir debido a muchos factores que contribuyen, y los problemas legales que siguen dependen de qui\u00e9n estuvo involucrado y qu\u00e9 estaba haciendo el conductor en el momento de la colisi\u00f3n. Manejamos toda la gama de reclamos por lesiones de viajes compartidos en Boca Rat\u00f3n y en todo el condado de Palm Beach.<\/p>\n<ul>\n<li><a href=\"https:\/\/warnerfitzmartin.com\/boca-raton-car-accident-lawyer\/\"><strong>Accidentes de coche<\/strong><\/a><strong>. <\/strong>Cuando un conductor de Uber causa una colisi\u00f3n con otro veh\u00edculo, la responsabilidad puede recaer en el conductor, la aseguradora corporativa de Uber o ambas. Investigamos el estado de la aplicaci\u00f3n en el momento del accidente, lo que determina qu\u00e9 nivel de seguro se aplica.<\/li>\n<\/ul>\n<ul>\n<li><strong>Accidentes con pasajeros en el veh\u00edculo<\/strong>. Los pasajeros que resulten lesionados durante un viaje activo est\u00e1n protegidos por la p\u00f3liza de responsabilidad civil de Uber, que cubre hasta un mill\u00f3n de d\u00f3lares. Sin embargo, para poder cobrar esa indemnizaci\u00f3n es necesario saber c\u00f3mo desenvolverse en un proceso de reclamaci\u00f3n corporativo que no est\u00e1 dise\u00f1ado para ayudarte.<\/li>\n<\/ul>\n<ul>\n<li><strong>Accidentes que involucran peatones o ciclistas<\/strong>. Ser atropellado por un veh\u00edculo de Uber como peat\u00f3n o ciclista a menudo resulta en lesiones graves. Manejamos accidentes de bicicleta y casos de peatones, sabiendo c\u00f3mo construir reclamos de responsabilidad civil cuando un conductor comercial est\u00e1 involucrado.<\/li>\n<\/ul>\n<ul>\n<li><strong>Accidentes multiveh\u00edculo con Uber<\/strong>. Cuando un veh\u00edculo de Uber forma parte de una colisi\u00f3n m\u00faltiple, presentar reclamaciones en <a href=\"https:\/\/warnerfitzmartin.com\/filing-claims-for-injuries-in-multi-car-accidents\/\">accidentes m\u00faltiples de autos<\/a> se vuelve significativamente m\u00e1s complicado. M\u00faltiples demandados y m\u00faltiples aseguradoras no siempre coinciden en qui\u00e9n es responsable y a qui\u00e9n se le adeuda el pago.<\/li>\n<\/ul>\n<ul>\n<li><strong>Accidentes causados por distracciones al volante<\/strong>. Los conductores de Uber pueden revisar su aplicaci\u00f3n constantemente para ver indicaciones o solicitudes de viaje en espera. Esto crea riesgos reales de distracci\u00f3n. Sabemos c\u00f3mo<a href=\"https:\/\/warnerfitzmartin.com\/hit-by-a-distracted-driver-how-cell-phone-data-can-win-your-auto-accident-case\/\"> usa datos del celular<\/a> y otras pruebas digitales para demostrar que el conductor no estaba prestando atenci\u00f3n en el momento del impacto.<\/li>\n<\/ul>\n<ul>\n<li><strong>Accidentes que resulten en lesiones catastr\u00f3ficas o muerte por negligencia<\/strong>. Cuando un accidente de Uber causa una lesi\u00f3n de la m\u00e9dula espinal, una lesi\u00f3n cerebral o un fallecimiento, las apuestas son altas. Estos casos requieren un nivel diferente de investigaci\u00f3n, la participaci\u00f3n de expertos m\u00e9dicos u otros, y un an\u00e1lisis de da\u00f1os a largo plazo.<\/li>\n<\/ul>\n<h2><strong>Requisitos legales de Florida para casos de accidentes de Uber<\/strong><\/h2>\n<p>Florida tiene un marco legal espec\u00edfico para accidentes de viajes compartidos bajo<a href=\"https:\/\/www.flsenate.gov\/laws\/statutes\/2017\/627.748\"> Estatuto de Florida \u00a7 627.748<\/a>. La cobertura disponible para usted despu\u00e9s de un accidente depende completamente de la fase en la que se encontraba el conductor cuando ocurri\u00f3 la colisi\u00f3n.<\/p>\n<p>Cuando la aplicaci\u00f3n del conductor de Uber est\u00e1 desactivada, solo se aplica su p\u00f3liza de seguro de autom\u00f3vil personal, y Uber no tiene ninguna obligaci\u00f3n en materia de seguro. Cuando el conductor est\u00e1 conectado y esperando una solicitud de viaje, Florida exige como m\u00ednimo $50,000 por persona en responsabilidad por lesiones corporales, $100,000 por accidente y $25,000 en da\u00f1os a la propiedad. Pero una vez que el conductor acepta un viaje y hasta que el pasajero sale del veh\u00edculo, la ley exige que Uber cuente con una cobertura de responsabilidad civil primaria de $1 mill\u00f3n. Esa distinci\u00f3n es de suma importancia para determinar la cantidad de indemnizaci\u00f3n a la que usted tiene derecho.<\/p>\n<p>Florida tambi\u00e9n opera bajo un est\u00e1ndar de negligencia comparativa modificada desde el 24 de marzo de 2023, bajo<a href=\"https:\/\/www.flsenate.gov\/Laws\/Statutes\/2023\/768.81\"> Estatuto de Florida \u00a7 768.81<\/a>. Si se determina que usted es responsable del accidente en m\u00e1s de un 50%, no podr\u00e1 obtener indemnizaci\u00f3n alguna por da\u00f1os y perjuicios. Los peritos de seguros conocen bien esta norma y tratar\u00e1n de atribuirle la culpa desde el principio del proceso. Esa es una de las razones por las que es importante consultar con un abogado antes de hacer cualquier declaraci\u00f3n grabada.<\/p>\n<p>Finalmente, el estatuto de limitaciones de Florida para reclamos por negligencia es de dos a\u00f1os a partir de la fecha del accidente, seg\u00fan<a href=\"https:\/\/www.flsenate.gov\/laws\/statutes\/2023\/95.11\"> Estatuto de Florida \u00a7 95.11<\/a> (para reclamos que ocurran el 24 de marzo de 2023 o despu\u00e9s). Si excede este plazo, ya no ser\u00e1 elegible para recibir compensaci\u00f3n. Existen excepciones muy limitadas, y la mayor\u00eda de ellas no aplican a casos de accidentes vehiculares est\u00e1ndar. No recomendamos confiar en que estos factores poco comunes se apliquen a su caso, y sugerimos que comencemos a construir su caso antes de que se acerque la fecha l\u00edmite.<\/p>\n<h2><strong>\u00bfQu\u00e9 da\u00f1os se pueden recuperar en un accidente de Uber en Boca Rat\u00f3n?<\/strong><\/h2>\n<p>Las v\u00edctimas de accidentes de Uber pueden buscar dos categor\u00edas principales de da\u00f1os, incluyendo los econ\u00f3micos y los no econ\u00f3micos. En casos raros que impliquen negligencia grave o conducta dolosa,<a href=\"https:\/\/warnerfitzmartin.com\/understanding-punitive-damages-in-gross-negligence-cases\/\"> da\u00f1os y perjuicios punitivos<\/a> tambi\u00e9n puede estar disponible.<\/p>\n<p><strong>Da\u00f1os econ\u00f3micos <\/strong>son las p\u00e9rdidas financieras documentadas que ha sufrido a causa del accidente. Los gastos m\u00e9dicos son los m\u00e1s comunes, e incluyen visitas a la sala de emergencias, cirug\u00edas, hospitalizaciones, rehabilitaci\u00f3n.<\/p>\n<p><strong>Da\u00f1os no econ\u00f3micos<\/strong> son m\u00e1s dif\u00edciles de cuantificar, pero a menudo representan la parte m\u00e1s grande de la reclamaci\u00f3n por lesiones graves. Estos incluyen dolor y sufrimiento, angustia emocional, p\u00e9rdida del disfrute de la vida y, en algunos casos, p\u00e9rdida de consorcio por el impacto en sus relaciones familiares. La ley de Florida permite la recuperaci\u00f3n total por estos da\u00f1os cuando la negligencia de otra parte caus\u00f3 sus lesiones.<\/p>\n<p>Adem\u00e1s, el sistema PIP de Florida se aplica a los accidentes de veh\u00edculos compartidos. Tu propia cobertura de protecci\u00f3n contra lesiones personales (PIP) cubre el 80 % de tus gastos m\u00e9dicos y el 60 % de los salarios perdidos, hasta un m\u00e1ximo de 10 000 d\u00f3lares, independientemente de qui\u00e9n tenga la culpa. Pero el PIP no cubre el dolor y el sufrimiento, y 10,000 d\u00f3lares se agotan r\u00e1pidamente despu\u00e9s de un accidente grave. Para reclamar una indemnizaci\u00f3n completa m\u00e1s all\u00e1 del PIP, sus lesiones deben cumplir con el umbral de lesiones graves de Florida. La mayor\u00eda de los casos que implican cirug\u00eda, da\u00f1o significativo a los tejidos blandos o discapacidad permanente cumplir\u00e1n con estos requisitos.<\/p>\n<h2><strong>Contacta a los Abogados de Lesiones Personales Warner &amp; Fitzmartin<\/strong><\/h2>\n<p>Si sufiste una lesi\u00f3n en un choque de Uber en Boca Rat\u00f3n o en cualquier parte del condado de Palm Beach, nuestro equipo est\u00e1 listo para ayudarte. En Warner &amp; Fitzmartin Personal Injury Lawyers, ofrecemos consultas gratuitas y no pagas nada a menos que ganemos tu caso. <a href=\"https:\/\/warnerfitzmartin.com\/contact-us\/\">Cont\u00e1ctanos<\/a> para contarnos lo que sucedi\u00f3 durante la colisi\u00f3n del viaje compartido y averiguar cu\u00e1nto podr\u00eda valer su caso. Esperamos hablar con usted de inmediato.<\/p>\n<h2 data-pm-slice=\"0 0 []\"><strong>Estad\u00edsticas de accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h2>\n<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-6685\" src=\"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/08\/Uber-accident-lawyer-in-Boca-Raton-FL-300x200.jpg\" alt=\"Abogado de accidentes de Uber en Boca Raton, FL\" width=\"300\" height=\"200\" srcset=\"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/08\/Uber-accident-lawyer-in-Boca-Raton-FL-300x200.jpg 300w, https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/08\/Uber-accident-lawyer-in-Boca-Raton-FL-768x512.jpg 768w, https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/08\/Uber-accident-lawyer-in-Boca-Raton-FL-18x12.jpg 18w, https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/08\/Uber-accident-lawyer-in-Boca-Raton-FL.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Los registros p\u00fablicos de accidentes rara vez separan las colisiones de viajes compartidos como su propia categor\u00eda, por lo que el panorama m\u00e1s claro proviene de datos m\u00e1s amplios sobre veh\u00edculos motorizados y distracciones. Esos datos a\u00fan dicen mucho sobre el riesgo. Un conductor de Uber pasa la jornada laboral mirando una pantalla, aceptando nuevas solicitudes de viaje y siguiendo indicaciones paso a paso, lo que sit\u00faa la distracci\u00f3n por la aplicaci\u00f3n en el centro de muchos de estos accidentes. El condado de Palm Beach registra un gran volumen de viajes compartidos durante todo el a\u00f1o, y Boca Raton atrae un flujo constante de viajes hacia y desde el aeropuerto, el centro y las playas.<\/p>\n<p>Las cifras a continuaci\u00f3n provienen de agencias de seguridad estatales y federales. Reflejan todos los accidentes de veh\u00edculos motorizados, no solo los de Uber, pero muestran con qu\u00e9 frecuencia la distracci\u00f3n y el error del conductor convierten un viaje ordinario en un reclamo por lesiones.<\/p>\n<ul>\n<li>Los accidentes causados por distracciones cobraron la vida de 3,208 personas en todo el pa\u00eds en 2024, seg\u00fan<a href=\"https:\/\/www.nhtsa.gov\/risky-driving\/distracted-driving\"> Datos de choques de NHTSA<\/a>.<\/li>\n<li>Alrededor de nueve personas mueren todos los d\u00edas en los Estados Unidos en colisiones en las que est\u00e1 involucrado un conductor distra\u00eddo, el<a href=\"https:\/\/www.cdc.gov\/distracted-driving\/about\/index.html\"> Informes de los CDC<\/a>.<\/li>\n<li>De las personas fallecidas en accidentes causados por distracciones en 2024, 639 eran peatones, ciclistas u otros usuarios fuera de un veh\u00edculo, seg\u00fan<a href=\"https:\/\/crashstats.nhtsa.dot.gov\/Api\/Public\/ViewPublication\/813790\"> datos de investigaci\u00f3n federal<\/a>.<\/li>\n<li>Las agencias de Florida registran cerca de 400,000 accidentes de tr\u00e1nsito en un a\u00f1o t\u00edpico, y el condado de Palm Beach se encuentra entre los condados con mayor volumen del estado, seg\u00fan<a href=\"https:\/\/www.fdot.gov\/Safety\/safetyengineering\/crash-data.shtm\"> Datos de accidentes en Florida<\/a>.<\/li>\n<\/ul>\n<h2><strong>Causas comunes de accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h2>\n<p>No hay dos accidentes de transporte compartido que sean exactamente iguales, pero siempre se repiten los mismos factores en los casos que analizamos. La causa es importante, porque a menudo indica qui\u00e9n es responsable y qu\u00e9 p\u00f3liza de seguro debe cubrir los da\u00f1os.<\/p>\n<ul>\n<li><strong>Distracci\u00f3n de la aplicaci\u00f3n.<\/strong> Un conductor de viajes compartidos revisa la pantalla para ver la pr\u00f3xima tarifa, lee las indicaciones y env\u00eda mensajes a los pasajeros, a veces todo en el espacio de unas pocas millas. Cada vistazo hacia abajo es tiempo que no se pasa mirando la carretera.<\/li>\n<li><strong>Fatiga.<\/strong> Muchos conductores trabajan turnos largos o manejan para Uber despu\u00e9s de otro trabajo de tiempo completo. Conducir con sue\u00f1o reduce el tiempo de reacci\u00f3n de maneras que se asemejan a la ebriedad.<\/li>\n<li><strong>Exceso de velocidad y prisa.<\/strong> El pago depende de los viajes completados. Ese incentivo lleva a algunos conductores a exceder la velocidad, pasarse de los sem\u00e1foros amarillos y realizar cambios de carril agresivos para reducir en unos minutos la duraci\u00f3n del viaje.<\/li>\n<li><strong>Rutas desconocidas.<\/strong> Los conductores siguen las indicaciones del GPS para entrar en vecindarios que no conocen, lo que provoca frenadas bruscas, giros fallidos y paradas en medio de carriles con tr\u00e1fico.<\/li>\n<li><strong>Recogidas y entregas inadecuadas.<\/strong> Cargar o descargar un pasajero en un carril de circulaci\u00f3n o en una ciclov\u00eda crea peligros para los ciclistas, motociclistas y otros conductores.<\/li>\n<li><strong>Conducir bajo los efectos del alcohol o de sustancias.<\/strong> La demanda de viajes compartidos alcanza su punto m\u00e1ximo por la noche y los fines de semana, y un conductor que no deber\u00eda estar al volante aumenta el peligro para todos en el auto.<\/li>\n<li><strong>Mal mantenimiento del veh\u00edculo.<\/strong> Uber establece las normas para los veh\u00edculos, pero el mantenimiento es responsabilidad de cada conductor. Las llantas desgastadas y los frenos defectuosos contribuyen a accidentes que nunca deber\u00edan haber ocurrido.<\/li>\n<li><strong>Condiciones de las carreteras en el sur de Florida.<\/strong> Los aguaceros repentinos, el agua estancada y el tr\u00e1fico estacional denso aumentan las probabilidades de un accidente grave en carreteras como Glades Road y Federal Highway.<\/li>\n<\/ul>\n<p>Cuando lleva su caso a un abogado de accidentes de Uber en Boca Raton, una de las primeras cosas que hacemos es determinar la causa. Si un conductor estaba distra\u00eddo o intoxicado, eso cambia el valor del reclamo y la forma en que tratamos con la aseguradora de Uber.<\/p>\n<h2><strong>Preguntas frecuentes sobre abogados de accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h2>\n<h3><strong>\u00bfTengo derecho a una indemnizaci\u00f3n si iba de pasajero en el Uber?<\/strong><\/h3>\n<p>S\u00ed. Los pasajeros casi nunca tienen la culpa en un accidente de viajes compartidos, lo que hace que estas sean de las reclamaciones m\u00e1s directas de entablar. Durante un viaje activo, se aplica la cobertura de Uber, y es posible que tambi\u00e9n tenga una reclamaci\u00f3n contra otro conductor que haya causado el choque. Un abogado de accidentes de Uber en Boca Raton puede determinar qu\u00e9 p\u00f3lizas le deben dinero.<\/p>\n<h3><strong>\u00bfCu\u00e1nto cuesta contratar a un abogado de accidentes de Uber en Boca Raton, FL?<\/strong><\/h3>\n<p>Nada por adelantado. Manejamos los casos de lesiones en viajes compartidos bajo la modalidad de honorarios de contingencia, por lo que usted no paga ninguna tarifa a menos que recuperemos una compensaci\u00f3n para usted. La primera consulta es gratuita y nosotros adelantamos los costos para construir su reclamo.<\/p>\n<h3><strong>\u00bfDeber\u00eda consultar a un m\u00e9dico aunque me sienta bien?<\/strong><\/h3>\n<p>S\u00ed. La adrenalina enmascara las lesiones despu\u00e9s de un choque y algunos s\u00edntomas aparecen despu\u00e9s.<a href=\"https:\/\/warnerfitzmartin.com\/what-if-i-feel-pain-days-after-the-car-accident-i-was-in\/\"> d\u00edas despu\u00e9s<\/a>. La atenci\u00f3n m\u00e9dica oportuna protege su salud y crea un registro que conecta sus lesiones con la colisi\u00f3n.<\/p>\n<h3><strong>\u00bfPuedo demandar al conductor de Uber directamente?<\/strong><\/h3>\n<p>A veces. Si puedes<a href=\"https:\/\/warnerfitzmartin.com\/can-i-sue-if-an-uber-or-lyft-rideshare-driver-hit-my-car\/\"> demandar a un conductor de un servicio de transporte compartido<\/a>, la aseguradora de Uber o un tercero, dependiendo de qui\u00e9n haya causado el accidente y de lo que estuviera haciendo el conductor en ese momento. Identificamos todas las fuentes de indemnizaci\u00f3n disponibles.<\/p>\n<h3><strong>\u00bfCu\u00e1nto tiempo tengo para presentar la solicitud?<\/strong><\/h3>\n<p>Florida otorga a la mayor\u00eda de las v\u00edctimas de lesiones <a href=\"https:\/\/www.flsenate.gov\/Laws\/Statutes\/2025\/0095.11\">dos a\u00f1os<\/a> desde la fecha del accidente para presentar una demanda. Si se demora, ser\u00e1 m\u00e1s dif\u00edcil reunir pruebas y localizar a los testigos. Cuanto antes comencemos, m\u00e1s s\u00f3lida ser\u00e1 su posici\u00f3n.<\/p>\n<h3><strong>\u00bfY si la aplicaci\u00f3n del conductor de Uber estuviera apagada?<\/strong><\/h3>\n<p>En ese caso, es probable que solo se aplique la p\u00f3liza de seguro de auto personal del conductor, y Uber por lo general no tiene ninguna obligaci\u00f3n. Estas situaciones se complican r\u00e1pidamente, y es \u00fatil contar con un<a href=\"https:\/\/warnerfitzmartin.com\/boca-raton-rideshare-accident-lawyer\/\"> abogado de accidentes de viajes compartidos<\/a> en Boca Raton, revise los registros de la aplicaci\u00f3n.<\/p>\n<h3><strong>\u00bfY si tuve parte de la culpa?<\/strong><\/h3>\n<p>A\u00fan puedes recuperarte. Florida sigue una <a href=\"https:\/\/www.flsenate.gov\/Laws\/Statutes\/2025\/768.81\">negligencia comparativa<\/a> regla, y siempre que no fuera usted responsable en m\u00e1s de la mitad, puede reclamar una indemnizaci\u00f3n reducida por su grado de culpa.<\/p>\n<h3><strong>\u00bfLa compa\u00f1\u00eda de seguros de Uber me representa?<\/strong><\/h3>\n<p>No. Sus ajustadores trabajan para limitar lo que paga la compa\u00f1\u00eda. Cualquier cosa que diga puede usarse para reducir su reclamo, por lo que es prudente hablar con un abogado antes de dar una declaraci\u00f3n grabada.<\/p>\n<h3><strong>\u00bfCu\u00e1nto vale mi caso de accidente de Uber en Boca Rat\u00f3n?<\/strong><\/h3>\n<p>Depende de la gravedad de sus lesiones, sus gastos m\u00e9dicos, la p\u00e9rdida de ingresos y c\u00f3mo el accidente ha afectado su vida diaria. Evaluamos todo eso antes de ponerle una cifra a la demanda.<\/p>\n<h3><strong>\u00bfQu\u00e9 pasa si un familiar muri\u00f3 en el accidente?<\/strong><\/h3>\n<p>Los familiares sobrevivientes pueden tener derecho a presentar una demanda por homicidio culposo. Manejamos estos asuntos con cuidado y podemos explicarle qui\u00e9n es elegible para presentarla y qu\u00e9 permite la ley recuperar.<\/p>\n<h2><strong>Recursos importantes para casos de accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h2>\n<h3><strong>Lugares m\u00e1s peligrosos para accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h3>\n<p>Los viajes de viajes compartidos se concentran donde el tr\u00e1fico es m\u00e1s pesado, y unos pocos corredores representan una gran parte de los choques que vemos. Los conductores y pasajeros deben mantenerse especialmente alerta a lo largo de estas rutas.<\/p>\n<p>Calles peligrosas:<\/p>\n<ul>\n<li><strong>Calle Glades.<\/strong> El tr\u00e1fico minorista constante cerca del centro comercial y el intercambio de la Interestatal 95 produce frecuentes choques de arranca y para.<\/li>\n<li><strong>Carretera Federal (US 1).<\/strong> Una densa mezcla de intersecciones, peatones y tr\u00e1fico que gira atraviesa el coraz\u00f3n de la ciudad.<\/li>\n<li><strong>Palmetto Park Road.<\/strong> Tr\u00e1fico pesado en el centro y rumbo a la playa, con giros cerrados y cruces peatonales concurridos.<\/li>\n<\/ul>\n<p>Carreteras peligrosas:<\/p>\n<ul>\n<li><strong>Interstate 95.<\/strong> Las altas velocidades y las desaceleraciones repentinas hacen que este sea el tramo m\u00e1s propenso a accidentes de la zona.<\/li>\n<li><strong>Florida\u2019s Turnpike.<\/strong> Tr\u00e1fico r\u00e1pido y frecuentes cambios de carril cerca del intercambio de Boca Rat\u00f3n.<\/li>\n<\/ul>\n<h3><strong>\u00bfCu\u00e1les son los recursos locales importantes para accidentes de Uber en Boca Raton?<\/strong><\/h3>\n<p>Si ha sufrido lesiones en un accidente de viaje compartido, unos cuantos contactos locales pueden ayudarle a documentar lo ocurrido y a recibir la atenci\u00f3n que necesita. Guarde esta informaci\u00f3n a la mano despu\u00e9s de cualquier colisi\u00f3n en el \u00e1rea.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.myboca.us\/2829\/Police\">Departamento de Servicios Policiales de Boca Rat\u00f3n<\/a>: 561-338-1234<\/li>\n<li><a href=\"https:\/\/baptisthealth.net\/locations\/hospitals\/boca-raton-regional-hospital\">Hospital Regional de Boca Rat\u00f3n<\/a>: 561-955-7100<\/li>\n<li><a href=\"https:\/\/www.pbso.org\/our-communities\/d7\">Oficina del Sheriff del Condado de Palm Beach<\/a>: 561-995-2800<\/li>\n<\/ul>\n<p>Warner &amp; Fitzmartin Personal Injury Lawyers no respalda ni est\u00e1 afiliado a ninguna de las organizaciones enumeradas anteriormente. Se proporcionan \u00fanicamente para su comodidad.<\/p>\n<h3><strong>Acerca de Warner &amp; Fitzmartin, abogados especializados en lesiones personales<\/strong><\/h3>\n<p>Los abogados de lesiones personales Warner &amp; Fitzmartin fueron fundados por dos abogados que representan a personas lesionadas y a sus familias, nunca a compa\u00f1\u00edas de seguros. Elissa Fitzmartin ocupa un puesto de liderazgo en el Colegio de Abogados del Sur del Condado de Palm Beach, donde es expresidenta de su Secci\u00f3n de Abogados J\u00f3venes, y es miembro de la Asociaci\u00f3n de Justicia del Condado de Palm Beach. Aaron Warner obtuvo su t\u00edtulo universitario en la Universidad de Florida Central antes de estudiar derecho en la Universidad de Miami. Nuestra firma ha recuperado<a href=\"https:\/\/warnerfitzmartin.com\/case-results\/\"> millones de d\u00f3lares<\/a> para clientes en toda la regi\u00f3n.<\/p>\n<h2><strong>Lo que dicen nuestros clientes<\/strong><\/h2>\n<p>\u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n<p><em>\u201cContrat\u00e9 a Warner &amp; Fitzmartin para mis reclamos por accidente automovil\u00edstico y da\u00f1os a la propiedad despu\u00e9s de que otro abogado me abandon\u00f3. Desde el primer d\u00eda planearon la estrategia y me mantuvieron informado de lo que suceder\u00eda y cu\u00e1ndo. Tras presionar para presentar una demanda contra la compa\u00f1\u00eda de seguros que negaba la culpa, consiguieron el l\u00edmite de la p\u00f3liza. Adem\u00e1s, me ayudaron a negociar un precio justo por los da\u00f1os de mi auto. Si quieres un abogado que luche por ti, \u00a1ll\u00e1malos!\u201d<\/em><\/p>\n<p>Marilyn Della Vedova, rese\u00f1a de Google verificada<\/p>\n<p>Lee m\u00e1s rese\u00f1as en nuestro<a href=\"https:\/\/maps.app.goo.gl\/b87XYUKqhDMeBg4s8\"> Perfil de Negocio de Google.<\/a><\/p>\n<h2><strong>Recursos adicionales para casos de accidentes de Uber en Boca Rat\u00f3n<\/strong><\/h2>\n<ul>\n<li><a href=\"https:\/\/warnerfitzmartin.com\/5-questions-for-your-uber-accident-consultation\/\">5 preguntas para tu consulta sobre un accidente de Uber<\/a><\/li>\n<li><a href=\"https:\/\/warnerfitzmartin.com\/understanding-rideshare-exclusions-in-insurance-policies\/\">Entendiendo las exclusiones de rideshare en las p\u00f3lizas de seguro<\/a><\/li>\n<li><a href=\"https:\/\/warnerfitzmartin.com\/can-a-florida-rideshare-lawyer-help-after-an-uber-or-lyft-crash\/\">\u00bfPuede un abogado de viajes compartidos en Florida ayudar despu\u00e9s de un accidente de Uber o Lyft<\/a><\/li>\n<li><a href=\"https:\/\/warnerfitzmartin.com\/key-factors-in-lyft-accident-liability\/\">Factores clave en la responsabilidad por accidentes de Lyft<\/a><\/li>\n<li><a href=\"https:\/\/warnerfitzmartin.com\/what-is-a-fair-settlement-for-pain-and-suffering\/\">\u00bfQu\u00e9 es un acuerdo justo por dolor y sufrimiento?<\/a><\/li>\n<\/ul>\n<h2><strong>Contacta a los Abogados de Lesiones Personales Warner &amp; Fitzmartin<\/strong><\/h2>\n<p>Un accidente de viaje compartido puede dejarle con facturas acumuladas y poca idea de qui\u00e9n es responsable de pagarlas. nuestro abogado de accidentes de Uber en Boca Rat\u00f3n examinar\u00e1 lo sucedido, le explicar\u00e1 sus opciones en t\u00e9rminos sencillos y se encargar\u00e1 de las aseguradoras para que usted pueda concentrarse en su recuperaci\u00f3n. La consulta es gratuita y no debe pagar ning\u00fan honorario a menos que recuperemos una compensaci\u00f3n para usted.<a href=\"https:\/\/warnerfitzmartin.com\/contact-us\/\"> Cont\u00e1ctanos<\/a> para guiarlo a trav\u00e9s de la colisi\u00f3n y averiguar cu\u00e1nto podr\u00eda valer su reclamo por accidente de viajes compartidos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Uber Accident Lawyer Boca Raton If you were hurt in an Uber crash in Boca Raton, then you may be dealing with serious injuries and are unsure how to pursue payment for your medical bills and other losses. Our Boca Raton, FL uber accident lawyer knows that when there is the added factor of a [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":6017,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"simple-practice-area.php","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-6016","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boca Raton Uber Accident Lawyer | Warner &amp; Fitzmartin Personal Injury Lawyers<\/title>\n<meta name=\"description\" content=\"Injured in an Uber crash in Boca Raton? Warner &amp; Fitzmartin Personal Injury Lawyers fights for full compensation. Millions recovered for Florida injury victims. Free consultation. No fees unless we win.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warnerfitzmartin.com\/es\/abogado-de-accidentes-de-uber-en-boca-raton\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boca Raton Uber Accident Lawyer | Warner &amp; Fitzmartin Personal Injury Lawyers\" \/>\n<meta property=\"og:description\" content=\"Injured in an Uber crash in Boca Raton? Warner &amp; Fitzmartin Personal Injury Lawyers fights for full compensation. Millions recovered for Florida injury victims. Free consultation. No fees unless we win.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warnerfitzmartin.com\/es\/abogado-de-accidentes-de-uber-en-boca-raton\/\" \/>\n<meta property=\"og:site_name\" content=\"Warner &amp; Fitzmartin Personal Injury Lawyers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/warnerfitzmartin\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T08:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/05\/uber-accident-lawyer-Boca-Raton-FL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/\",\"url\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/\",\"name\":\"Boca Raton Uber Accident Lawyer | Warner &amp; Fitzmartin Personal Injury Lawyers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/warnerfitzmartin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uber-accident-lawyer-Boca-Raton-FL.jpg\",\"datePublished\":\"2026-05-01T19:51:44+00:00\",\"dateModified\":\"2026-08-27T08:38:00+00:00\",\"description\":\"Injured in an Uber crash in Boca Raton? Warner & Fitzmartin Personal Injury Lawyers fights for full compensation. Millions recovered for Florida injury victims. Free consultation. No fees unless we win.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/warnerfitzmartin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uber-accident-lawyer-Boca-Raton-FL.jpg\",\"contentUrl\":\"https:\\\/\\\/warnerfitzmartin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uber-accident-lawyer-Boca-Raton-FL.jpg\",\"width\":1000,\"height\":667,\"caption\":\"uber accident lawyer Boca Raton, FL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/boca-raton-uber-accident-lawyer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/warnerfitzmartin.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boca Raton Uber Accident Lawyer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/#website\",\"url\":\"https:\\\/\\\/warnerfitzmartin.com\\\/\",\"name\":\"Warner & Fitzmartin Personal Injury Lawyers\",\"description\":\"Florida Personal Injury Attorneys\",\"publisher\":{\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/warnerfitzmartin.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/#organization\",\"name\":\"Warner & Fitzmartin Personal Injury Lawyers\",\"url\":\"https:\\\/\\\/warnerfitzmartin.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/warnerfitzmartin.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Group-1.png\",\"contentUrl\":\"https:\\\/\\\/warnerfitzmartin.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Group-1.png\",\"width\":903,\"height\":240,\"caption\":\"Warner & Fitzmartin Personal Injury Lawyers\"},\"image\":{\"@id\":\"https:\\\/\\\/warnerfitzmartin.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/warnerfitzmartin\",\"https:\\\/\\\/www.instagram.com\\\/warnerfitzmartin\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/warner-fitzmartin-pllc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@WarnerFitzmartin\",\"https:\\\/\\\/maps.app.goo.gl\\\/PWybDLgTE6Zz6vig9\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogado de Accidentes de Uber en Boca Raton | Warner &amp; Fitzmartin Abogados de Lesiones Personales","description":"\u00bfLesionado en un accidente de Uber en Boca Raton? Warner &amp; Fitzmartin Personal Injury Lawyers lucha por una compensaci\u00f3n total. Millones recuperados para v\u00edctimas de lesiones en Florida. Consulta gratis. Sin honorarios a menos que ganemos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warnerfitzmartin.com\/es\/abogado-de-accidentes-de-uber-en-boca-raton\/","og_locale":"es_MX","og_type":"article","og_title":"Boca Raton Uber Accident Lawyer | Warner &amp; Fitzmartin Personal Injury Lawyers","og_description":"Injured in an Uber crash in Boca Raton? Warner & Fitzmartin Personal Injury Lawyers fights for full compensation. Millions recovered for Florida injury victims. Free consultation. No fees unless we win.","og_url":"https:\/\/warnerfitzmartin.com\/es\/abogado-de-accidentes-de-uber-en-boca-raton\/","og_site_name":"Warner &amp; Fitzmartin Personal Injury Lawyers","article_publisher":"https:\/\/www.facebook.com\/warnerfitzmartin","article_modified_time":"2026-08-27T08:38:00+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/05\/uber-accident-lawyer-Boca-Raton-FL.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/","url":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/","name":"Abogado de Accidentes de Uber en Boca Raton | Warner &amp; Fitzmartin Abogados de Lesiones Personales","isPartOf":{"@id":"https:\/\/warnerfitzmartin.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/#primaryimage"},"image":{"@id":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/#primaryimage"},"thumbnailUrl":"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/05\/uber-accident-lawyer-Boca-Raton-FL.jpg","datePublished":"2026-05-01T19:51:44+00:00","dateModified":"2026-08-27T08:38:00+00:00","description":"\u00bfLesionado en un accidente de Uber en Boca Raton? Warner &amp; Fitzmartin Personal Injury Lawyers lucha por una compensaci\u00f3n total. Millones recuperados para v\u00edctimas de lesiones en Florida. Consulta gratis. Sin honorarios a menos que ganemos.","breadcrumb":{"@id":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/#primaryimage","url":"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/05\/uber-accident-lawyer-Boca-Raton-FL.jpg","contentUrl":"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2026\/05\/uber-accident-lawyer-Boca-Raton-FL.jpg","width":1000,"height":667,"caption":"uber accident lawyer Boca Raton, FL"},{"@type":"BreadcrumbList","@id":"https:\/\/warnerfitzmartin.com\/boca-raton-uber-accident-lawyer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/warnerfitzmartin.com\/"},{"@type":"ListItem","position":2,"name":"Boca Raton Uber Accident Lawyer"}]},{"@type":"WebSite","@id":"https:\/\/warnerfitzmartin.com\/#website","url":"https:\/\/warnerfitzmartin.com\/","name":"Abogados de Lesiones Personales de Warner &amp; Fitzmartin","description":"Abogados de Lesiones Personales en Florida","publisher":{"@id":"https:\/\/warnerfitzmartin.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warnerfitzmartin.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/warnerfitzmartin.com\/#organization","name":"Abogados de Lesiones Personales de Warner &amp; Fitzmartin","url":"https:\/\/warnerfitzmartin.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/warnerfitzmartin.com\/#\/schema\/logo\/image\/","url":"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2025\/07\/Group-1.png","contentUrl":"https:\/\/warnerfitzmartin.com\/wp-content\/uploads\/2025\/07\/Group-1.png","width":903,"height":240,"caption":"Warner & Fitzmartin Personal Injury Lawyers"},"image":{"@id":"https:\/\/warnerfitzmartin.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/warnerfitzmartin","https:\/\/www.instagram.com\/warnerfitzmartin\/","https:\/\/www.linkedin.com\/company\/warner-fitzmartin-pllc\/","https:\/\/www.youtube.com\/@WarnerFitzmartin","https:\/\/maps.app.goo.gl\/PWybDLgTE6Zz6vig9"]}]}},"_links":{"self":[{"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/pages\/6016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/comments?post=6016"}],"version-history":[{"count":2,"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/pages\/6016\/revisions"}],"predecessor-version":[{"id":6686,"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/pages\/6016\/revisions\/6686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/media\/6017"}],"wp:attachment":[{"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/media?parent=6016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/warnerfitzmartin.com\/es\/wp-json\/wp\/v2\/categories?post=6016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}